{"id":1,"count":671,"description":"","link":"https:\/\/www.bvvizela.pt\/site\/category\/noticias\/","name":"Noticias","slug":"noticias","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.bvvizela.pt\/site\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bvvizela.pt\/site\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.bvvizela.pt\/site\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.bvvizela.pt\/site\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}